{"id":134676,"date":"2018-08-13T01:13:12","date_gmt":"2018-08-13T01:13:12","guid":{"rendered":"https:\/\/www.esteegel.com\/zipcode\/dampara-kurmin-sauri-ibi-taraba-state-postal-code\/"},"modified":"2018-08-13T01:13:12","modified_gmt":"2018-08-13T01:13:12","slug":"dampara-kurmin-sauri-ibi-taraba-state-postal-code","status":"publish","type":"post","link":"https:\/\/www.esteegel.com\/zipcode\/dampara-kurmin-sauri-ibi-taraba-state-postal-code\/","title":{"rendered":"Dampara &#8211; Kurmin-Sauri, Ibi, Taraba state Postal Code"},"content":{"rendered":"<p>Dampara \u2013  Kurmin-Sauri  Ibi,  Taraba Postal Code and Zip Code<\/p>\n<p><strong>670111<\/strong><\/p>\n<table class=\"table\">\n<tbody>\n<tr>\n<td width=\"200px\">District Name:<\/td>\n<td>District: Dampara \u2013 Kurmin-Sauri<\/td>\n<\/tr>\n<tr>\n<td>Town:<\/td>\n<td>Kurmin-Sauri<\/td>\n<\/tr>\n<tr>\n<td>Local Government Area:<\/td>\n<td>Ibi L.G.A<\/td>\n<\/tr>\n<tr>\n<td>State:<\/td>\n<td>Taraba State<\/td>\n<\/tr>\n<tr>\n<td>Country<strong>:<\/strong><\/td>\n<td>Nigeria<\/td>\n<\/tr>\n<tr>\n<td>Associated Zip Code<strong>:<\/strong><\/td>\n<td><strong>670111<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>This is the Postal code  and zip code of Dampara  in  Kurmin-Sauri town of Kurmin-Sauri L.G.A of Taraba state.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dampara \u2013 Kurmin-Sauri Ibi, Taraba Postal Code and Zip Code 670111 District Name: District: Dampara \u2013 Kurmin-Sauri Town: Kurmin-Sauri Local Government Area: Ibi L.G.A State: Taraba State Country: Nigeria Associated Zip Code: 670111 This is the Postal code and zip code of Dampara in Kurmin-Sauri town of Kurmin-Sauri L.G.A of Taraba state.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1418,1412],"tags":[],"class_list":["post-134676","post","type-post","status-publish","format-standard","hentry","category-ibi-l-g-a","category-taraba-state"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paaCEa-z2c","jetpack-related-posts":[{"id":134658,"url":"https:\/\/www.esteegel.com\/zipcode\/dampara-dampar-ibi-taraba-state-postal-code\/","url_meta":{"origin":134676,"position":0},"title":"Dampara &#8211; Dampar, Ibi, Taraba state Postal Code","author":"admin","date":"August 13, 2018","format":false,"excerpt":"Dampara \u2013 Dampar Ibi, Taraba Postal Code and Zip Code 670111 District Name: District: Dampara \u2013 Dampar Town: Dampar Local Government Area: Ibi L.G.A State: Taraba State Country: Nigeria Associated Zip Code: 670111 This is the Postal code and zip code of Dampara in Dampar town of Dampar L.G.A of\u2026","rel":"","context":"In &quot;Ibi L.G.A&quot;","block_context":{"text":"Ibi L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/taraba-state\/ibi-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":134678,"url":"https:\/\/www.esteegel.com\/zipcode\/dampara-mavo-ibi-taraba-state-postal-code\/","url_meta":{"origin":134676,"position":1},"title":"Dampara &#8211; Mavo, Ibi, Taraba state Postal Code","author":"admin","date":"August 13, 2018","format":false,"excerpt":"Dampara \u2013 Mavo Ibi, Taraba Postal Code and Zip Code 670111 District Name: District: Dampara \u2013 Mavo Town: Mavo Local Government Area: Ibi L.G.A State: Taraba State Country: Nigeria Associated Zip Code: 670111 This is the Postal code and zip code of Dampara in Mavo town of Mavo L.G.A of\u2026","rel":"","context":"In &quot;Ibi L.G.A&quot;","block_context":{"text":"Ibi L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/taraba-state\/ibi-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":134661,"url":"https:\/\/www.esteegel.com\/zipcode\/dampara-farin-ruwa-ibi-taraba-state-postal-code\/","url_meta":{"origin":134676,"position":2},"title":"Dampara &#8211; Farin-Ruwa, Ibi, Taraba state Postal Code","author":"admin","date":"August 13, 2018","format":false,"excerpt":"Dampara \u2013 Farin-Ruwa Ibi, Taraba Postal Code and Zip Code 670111 District Name: District: Dampara \u2013 Farin-Ruwa Town: Farin-Ruwa Local Government Area: Ibi L.G.A State: Taraba State Country: Nigeria Associated Zip Code: 670111 This is the Postal code and zip code of Dampara in Farin-Ruwa town of Farin-Ruwa L.G.A of\u2026","rel":"","context":"In &quot;Ibi L.G.A&quot;","block_context":{"text":"Ibi L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/taraba-state\/ibi-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":134663,"url":"https:\/\/www.esteegel.com\/zipcode\/dampara-gidan-alhaji-ibi-taraba-state-postal-code\/","url_meta":{"origin":134676,"position":3},"title":"Dampara &#8211; Gidan-Alhaji, Ibi, Taraba state Postal Code","author":"admin","date":"August 13, 2018","format":false,"excerpt":"Dampara \u2013 Gidan-Alhaji Ibi, Taraba Postal Code and Zip Code 670111 District Name: District: Dampara \u2013 Gidan-Alhaji Town: Gidan-Alhaji Local Government Area: Ibi L.G.A State: Taraba State Country: Nigeria Associated Zip Code: 670111 This is the Postal code and zip code of Dampara in Gidan-Alhaji town of Gidan-Alhaji L.G.A of\u2026","rel":"","context":"In &quot;Ibi L.G.A&quot;","block_context":{"text":"Ibi L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/taraba-state\/ibi-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":134664,"url":"https:\/\/www.esteegel.com\/zipcode\/dampara-gidan-dangiwa-ibi-taraba-state-postal-code\/","url_meta":{"origin":134676,"position":4},"title":"Dampara &#8211; Gidan-Dangiwa, Ibi, Taraba state Postal Code","author":"admin","date":"August 13, 2018","format":false,"excerpt":"Dampara \u2013 Gidan-Dangiwa Ibi, Taraba Postal Code and Zip Code 670111 District Name: District: Dampara \u2013 Gidan-Dangiwa Town: Gidan-Dangiwa Local Government Area: Ibi L.G.A State: Taraba State Country: Nigeria Associated Zip Code: 670111 This is the Postal code and zip code of Dampara in Gidan-Dangiwa town of Gidan-Dangiwa L.G.A of\u2026","rel":"","context":"In &quot;Ibi L.G.A&quot;","block_context":{"text":"Ibi L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/taraba-state\/ibi-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":134670,"url":"https:\/\/www.esteegel.com\/zipcode\/dampara-kauyen-dodo-ibi-taraba-state-postal-code\/","url_meta":{"origin":134676,"position":5},"title":"Dampara &#8211; Kauyen-Dodo, Ibi, Taraba state Postal Code","author":"admin","date":"August 13, 2018","format":false,"excerpt":"Dampara \u2013 Kauyen-Dodo Ibi, Taraba Postal Code and Zip Code 670111 District Name: District: Dampara \u2013 Kauyen-Dodo Town: Kauyen-Dodo Local Government Area: Ibi L.G.A State: Taraba State Country: Nigeria Associated Zip Code: 670111 This is the Postal code and zip code of Dampara in Kauyen-Dodo town of Kauyen-Dodo L.G.A of\u2026","rel":"","context":"In &quot;Ibi L.G.A&quot;","block_context":{"text":"Ibi L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/taraba-state\/ibi-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/134676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/comments?post=134676"}],"version-history":[{"count":0,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/134676\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/media?parent=134676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/categories?post=134676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/tags?post=134676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}