{"id":87159,"date":"2018-08-12T22:14:40","date_gmt":"2018-08-12T22:14:40","guid":{"rendered":"https:\/\/www.esteegel.com\/zipcode\/achina-ebene-aguata-anambra-state-postal-code\/"},"modified":"2018-08-12T22:14:40","modified_gmt":"2018-08-12T22:14:40","slug":"achina-ebene-aguata-anambra-state-postal-code","status":"publish","type":"post","link":"https:\/\/www.esteegel.com\/zipcode\/achina-ebene-aguata-anambra-state-postal-code\/","title":{"rendered":"Achina &#8211; Ebene, Aguata, Anambra state Postal Code"},"content":{"rendered":"<p>Achina \u2013  Ebene  Aguata,  Anambra Postal Code and Zip Code<\/p>\n<p><strong>422120<\/strong><\/p>\n<table class=\"table\">\n<tbody>\n<tr>\n<td width=\"200px\">District Name:<\/td>\n<td>District: Achina \u2013 Ebene<\/td>\n<\/tr>\n<tr>\n<td>Town:<\/td>\n<td>Ebene<\/td>\n<\/tr>\n<tr>\n<td>Local Government Area:<\/td>\n<td>Aguata L.G.A<\/td>\n<\/tr>\n<tr>\n<td>State:<\/td>\n<td>Anambra State<\/td>\n<\/tr>\n<tr>\n<td>Country<strong>:<\/strong><\/td>\n<td>Nigeria<\/td>\n<\/tr>\n<tr>\n<td>Associated Zip Code<strong>:<\/strong><\/td>\n<td><strong>422120<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>This is the Postal code  and zip code of Achina  in  Ebene town of Ebene L.G.A of Anambra state.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Achina \u2013 Ebene Aguata, Anambra Postal Code and Zip Code 422120 District Name: District: Achina \u2013 Ebene Town: Ebene Local Government Area: Aguata L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 422120 This is the Postal code and zip code of Achina in Ebene town of Ebene L.G.A of Anambra state.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[792,791],"tags":[],"class_list":["post-87159","post","type-post","status-publish","format-standard","hentry","category-aguata-l-g-a","category-anambra-state"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paaCEa-mFN","jetpack-related-posts":[{"id":87146,"url":"https:\/\/www.esteegel.com\/zipcode\/ekwulobia-aguata-aguata-anambra-state-postal-code\/","url_meta":{"origin":87159,"position":0},"title":"Ekwulobia &#8211; Aguata, Aguata, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ekwulobia \u2013 Aguata Aguata, Anambra Postal Code and Zip Code 422111 District Name: District: Ekwulobia \u2013 Aguata Town: Aguata Local Government Area: Aguata L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 422111 This is the Postal code and zip code of Ekwulobia in Aguata town of Aguata L.G.A of\u2026","rel":"","context":"In &quot;Aguata L.G.A&quot;","block_context":{"text":"Aguata L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/aguata-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":87142,"url":"https:\/\/www.esteegel.com\/zipcode\/ekwulobia-abaogwuoma-aguata-anambra-state-postal-code\/","url_meta":{"origin":87159,"position":1},"title":"Ekwulobia &#8211; Abaogwuoma, Aguata, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ekwulobia \u2013 Abaogwuoma Aguata, Anambra Postal Code and Zip Code 422111 District Name: District: Ekwulobia \u2013 Abaogwuoma Town: Abaogwuoma Local Government Area: Aguata L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 422111 This is the Postal code and zip code of Ekwulobia in Abaogwuoma town of Abaogwuoma L.G.A of\u2026","rel":"","context":"In &quot;Aguata L.G.A&quot;","block_context":{"text":"Aguata L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/aguata-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":87143,"url":"https:\/\/www.esteegel.com\/zipcode\/umuchu-achara-aguata-anambra-state-postal-code\/","url_meta":{"origin":87159,"position":2},"title":"Umuchu &#8211; Achara, Aguata, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Umuchu \u2013 Achara Aguata, Anambra Postal Code and Zip Code 422123 District Name: District: Umuchu \u2013 Achara Town: Achara Local Government Area: Aguata L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 422123 This is the Postal code and zip code of Umuchu in Achara town of Achara L.G.A of\u2026","rel":"","context":"In &quot;Aguata L.G.A&quot;","block_context":{"text":"Aguata L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/aguata-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":87144,"url":"https:\/\/www.esteegel.com\/zipcode\/ekwulobia-agba-aguata-anambra-state-postal-code\/","url_meta":{"origin":87159,"position":3},"title":"Ekwulobia &#8211; Agba, Aguata, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ekwulobia \u2013 Agba Aguata, Anambra Postal Code and Zip Code 422111 District Name: District: Ekwulobia \u2013 Agba Town: Agba Local Government Area: Aguata L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 422111 This is the Postal code and zip code of Ekwulobia in Agba town of Agba L.G.A of\u2026","rel":"","context":"In &quot;Aguata L.G.A&quot;","block_context":{"text":"Aguata L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/aguata-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":87145,"url":"https:\/\/www.esteegel.com\/zipcode\/akpu-agbaelu-aguata-anambra-state-postal-code\/","url_meta":{"origin":87159,"position":4},"title":"Akpu &#8211; Agbaelu, Aguata, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Akpu \u2013 Agbaelu Aguata, Anambra Postal Code and Zip Code 422119 District Name: District: Akpu \u2013 Agbaelu Town: Agbaelu Local Government Area: Aguata L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 422119 This is the Postal code and zip code of Akpu in Agbaelu town of Agbaelu L.G.A of\u2026","rel":"","context":"In &quot;Aguata L.G.A&quot;","block_context":{"text":"Aguata L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/aguata-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":87147,"url":"https:\/\/www.esteegel.com\/zipcode\/ezinifite-aku-aguata-anambra-state-postal-code\/","url_meta":{"origin":87159,"position":5},"title":"Ezinifite &#8211; Aku, Aguata, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ezinifite \u2013 Aku Aguata, Anambra Postal Code and Zip Code 422115 District Name: District: Ezinifite \u2013 Aku Town: Aku Local Government Area: Aguata L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 422115 This is the Postal code and zip code of Ezinifite in Aku town of Aku L.G.A of\u2026","rel":"","context":"In &quot;Aguata L.G.A&quot;","block_context":{"text":"Aguata L.G.A","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/aguata-l-g-a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/87159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/comments?post=87159"}],"version-history":[{"count":0,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/87159\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/media?parent=87159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/categories?post=87159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/tags?post=87159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}