{"id":87754,"date":"2018-08-12T22:17:54","date_gmt":"2018-08-12T22:17:54","guid":{"rendered":"https:\/\/www.esteegel.com\/zipcode\/osumoghu-eziala-ihiala-anambra-state-postal-code\/"},"modified":"2018-08-12T22:17:54","modified_gmt":"2018-08-12T22:17:54","slug":"osumoghu-eziala-ihiala-anambra-state-postal-code","status":"publish","type":"post","link":"https:\/\/www.esteegel.com\/zipcode\/osumoghu-eziala-ihiala-anambra-state-postal-code\/","title":{"rendered":"Osumoghu &#8211; Eziala, Ihiala, Anambra state Postal Code"},"content":{"rendered":"<p>Osumoghu \u2013  Eziala  Ihiala,  Anambra Postal Code and Zip Code<\/p>\n<p><strong>431123<\/strong><\/p>\n<table class=\"table\">\n<tbody>\n<tr>\n<td width=\"200px\">District Name:<\/td>\n<td>District: Osumoghu \u2013 Eziala<\/td>\n<\/tr>\n<tr>\n<td>Town:<\/td>\n<td>Eziala<\/td>\n<\/tr>\n<tr>\n<td>Local Government Area:<\/td>\n<td>Ihiala L.G.A<\/td>\n<\/tr>\n<tr>\n<td>State:<\/td>\n<td>Anambra State<\/td>\n<\/tr>\n<tr>\n<td>Country<strong>:<\/strong><\/td>\n<td>Nigeria<\/td>\n<\/tr>\n<tr>\n<td>Associated Zip Code<strong>:<\/strong><\/td>\n<td><strong>431123<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>This is the Postal code  and zip code of Osumoghu  in  Eziala town of Eziala L.G.A of Anambra state.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Osumoghu \u2013 Eziala Ihiala, Anambra Postal Code and Zip Code 431123 District Name: District: Osumoghu \u2013 Eziala Town: Eziala Local Government Area: Ihiala L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 431123 This is the Postal code and zip code of Osumoghu in Eziala town of Eziala L.G.A of Anambra state.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[791,803],"tags":[],"class_list":["post-87754","post","type-post","status-publish","format-standard","hentry","category-anambra-state","category-ihiala-l-g-a"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paaCEa-mPo","jetpack-related-posts":[{"id":87818,"url":"https:\/\/www.esteegel.com\/zipcode\/osumoghu-umudi-ihiala-anambra-state-postal-code\/","url_meta":{"origin":87754,"position":0},"title":"Osumoghu &#8211; Umudi, Ihiala, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Osumoghu \u2013 Umudi Ihiala, Anambra Postal Code and Zip Code 431123 District Name: District: Osumoghu \u2013 Umudi Town: Umudi Local Government Area: Ihiala L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 431123 This is the Postal code and zip code of Osumoghu in Umudi town of Umudi L.G.A of\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":87742,"url":"https:\/\/www.esteegel.com\/zipcode\/osumoghu-akwalihu-ihiala-anambra-state-postal-code\/","url_meta":{"origin":87754,"position":1},"title":"Osumoghu &#8211; Akwalihu, Ihiala, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Osumoghu \u2013 Akwalihu Ihiala, Anambra Postal Code and Zip Code 431123 District Name: District: Osumoghu \u2013 Akwalihu Town: Akwalihu Local Government Area: Ihiala L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 431123 This is the Postal code and zip code of Osumoghu in Akwalihu town of Akwalihu L.G.A of\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":87743,"url":"https:\/\/www.esteegel.com\/zipcode\/osumoghu-amadunu-ihiala-anambra-state-postal-code\/","url_meta":{"origin":87754,"position":2},"title":"Osumoghu &#8211; Amadunu, Ihiala, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Osumoghu \u2013 Amadunu Ihiala, Anambra Postal Code and Zip Code 431123 District Name: District: Osumoghu \u2013 Amadunu Town: Amadunu Local Government Area: Ihiala L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 431123 This is the Postal code and zip code of Osumoghu in Amadunu town of Amadunu L.G.A of\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":87748,"url":"https:\/\/www.esteegel.com\/zipcode\/osumoghu-ebenator-ihiala-anambra-state-postal-code\/","url_meta":{"origin":87754,"position":3},"title":"Osumoghu &#8211; Ebenator, Ihiala, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Osumoghu \u2013 Ebenator Ihiala, Anambra Postal Code and Zip Code 431123 District Name: District: Osumoghu \u2013 Ebenator Town: Ebenator Local Government Area: Ihiala L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 431123 This is the Postal code and zip code of Osumoghu in Ebenator town of Ebenator L.G.A of\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":87764,"url":"https:\/\/www.esteegel.com\/zipcode\/osumoghu-ihuoweri-ihiala-anambra-state-postal-code\/","url_meta":{"origin":87754,"position":4},"title":"Osumoghu &#8211; Ihuoweri, Ihiala, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Osumoghu \u2013 Ihuoweri Ihiala, Anambra Postal Code and Zip Code 431123 District Name: District: Osumoghu \u2013 Ihuoweri Town: Ihuoweri Local Government Area: Ihiala L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 431123 This is the Postal code and zip code of Osumoghu in Ihuoweri town of Ihuoweri L.G.A of\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":87766,"url":"https:\/\/www.esteegel.com\/zipcode\/osumoghu-initesha-ihiala-anambra-state-postal-code\/","url_meta":{"origin":87754,"position":5},"title":"Osumoghu &#8211; Initesha, Ihiala, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Osumoghu \u2013 Initesha Ihiala, Anambra Postal Code and Zip Code 431123 District Name: District: Osumoghu \u2013 Initesha Town: Initesha Local Government Area: Ihiala L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 431123 This is the Postal code and zip code of Osumoghu in Initesha town of Initesha L.G.A of\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/87754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/comments?post=87754"}],"version-history":[{"count":0,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/87754\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/media?parent=87754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/categories?post=87754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/tags?post=87754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}