{"id":88064,"date":"2018-08-12T22:17:54","date_gmt":"2018-08-12T22:17:54","guid":{"rendered":"https:\/\/www.esteegel.com\/zipcode\/awa-agbada-orumba-north-anambra-state-postal-code\/"},"modified":"2018-08-12T22:17:54","modified_gmt":"2018-08-12T22:17:54","slug":"awa-agbada-orumba-north-anambra-state-postal-code","status":"publish","type":"post","link":"https:\/\/www.esteegel.com\/zipcode\/awa-agbada-orumba-north-anambra-state-postal-code\/","title":{"rendered":"Awa &#8211; Agbada, Orumba North, Anambra state Postal Code"},"content":{"rendered":"<p>Awa \u2013  Agbada  Orumba North,  Anambra Postal Code and Zip Code<\/p>\n<p><strong>423129<\/strong><\/p>\n<table class=\"table\">\n<tbody>\n<tr>\n<td width=\"200px\">District Name:<\/td>\n<td>District: Awa \u2013 Agbada<\/td>\n<\/tr>\n<tr>\n<td>Town:<\/td>\n<td>Agbada<\/td>\n<\/tr>\n<tr>\n<td>Local Government Area:<\/td>\n<td>Orumba North L.G.A<\/td>\n<\/tr>\n<tr>\n<td>State:<\/td>\n<td>Anambra State<\/td>\n<\/tr>\n<tr>\n<td>Country<strong>:<\/strong><\/td>\n<td>Nigeria<\/td>\n<\/tr>\n<tr>\n<td>Associated Zip Code<strong>:<\/strong><\/td>\n<td><strong>423129<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>This is the Postal code  and zip code of Awa  in  Agbada town of Agbada L.G.A of Anambra state.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Awa \u2013 Agbada Orumba North, Anambra Postal Code and Zip Code 423129 District Name: District: Awa \u2013 Agbada Town: Agbada Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423129 This is the Postal code and zip code of Awa in Agbada town of Agbada L.G.A of Anambra state.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[791,808],"tags":[],"class_list":["post-88064","post","type-post","status-publish","format-standard","hentry","category-anambra-state","category-orumba-north-l-g-a"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paaCEa-mUo","jetpack-related-posts":[{"id":88065,"url":"https:\/\/www.esteegel.com\/zipcode\/awa-agbanokwe-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88064,"position":0},"title":"Awa &#8211; Agbanokwe, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Awa \u2013 Agbanokwe Orumba North, Anambra Postal Code and Zip Code 423129 District Name: District: Awa \u2013 Agbanokwe Town: Agbanokwe Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423129 This is the Postal code and zip code of Awa in Agbanokwe town of Agbanokwe\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88070,"url":"https:\/\/www.esteegel.com\/zipcode\/awa-ajango-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88064,"position":1},"title":"Awa &#8211; Ajango, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Awa \u2013 Ajango Orumba North, Anambra Postal Code and Zip Code 423129 District Name: District: Awa \u2013 Ajango Town: Ajango Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423129 This is the Postal code and zip code of Awa in Ajango town of Ajango\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88072,"url":"https:\/\/www.esteegel.com\/zipcode\/awa-akwulofia-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88064,"position":2},"title":"Awa &#8211; Akwulofia, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Awa \u2013 Akwulofia Orumba North, Anambra Postal Code and Zip Code 423129 District Name: District: Awa \u2013 Akwulofia Town: Akwulofia Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423129 This is the Postal code and zip code of Awa in Akwulofia town of Akwulofia\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88077,"url":"https:\/\/www.esteegel.com\/zipcode\/awa-amoji-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88064,"position":3},"title":"Awa &#8211; Amoji, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Awa \u2013 Amoji Orumba North, Anambra Postal Code and Zip Code 423129 District Name: District: Awa \u2013 Amoji Town: Amoji Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423129 This is the Postal code and zip code of Awa in Amoji town of Amoji\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88084,"url":"https:\/\/www.esteegel.com\/zipcode\/awa-egbeagu-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88064,"position":4},"title":"Awa &#8211; Egbeagu, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Awa \u2013 Egbeagu Orumba North, Anambra Postal Code and Zip Code 423129 District Name: District: Awa \u2013 Egbeagu Town: Egbeagu Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423129 This is the Postal code and zip code of Awa in Egbeagu town of Egbeagu\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88093,"url":"https:\/\/www.esteegel.com\/zipcode\/awa-eziobiuno-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88064,"position":5},"title":"Awa &#8211; Eziobiuno, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Awa \u2013 Eziobiuno Orumba North, Anambra Postal Code and Zip Code 423129 District Name: District: Awa \u2013 Eziobiuno Town: Eziobiuno Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423129 This is the Postal code and zip code of Awa in Eziobiuno town of Eziobiuno\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/88064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/comments?post=88064"}],"version-history":[{"count":0,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/88064\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/media?parent=88064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/categories?post=88064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/tags?post=88064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}