{"id":88145,"date":"2018-08-12T22:17:54","date_gmt":"2018-08-12T22:17:54","guid":{"rendered":"https:\/\/www.esteegel.com\/zipcode\/ajalli-uhuana-orumba-north-anambra-state-postal-code\/"},"modified":"2018-08-12T22:17:54","modified_gmt":"2018-08-12T22:17:54","slug":"ajalli-uhuana-orumba-north-anambra-state-postal-code","status":"publish","type":"post","link":"https:\/\/www.esteegel.com\/zipcode\/ajalli-uhuana-orumba-north-anambra-state-postal-code\/","title":{"rendered":"Ajalli &#8211; Uhuana, Orumba North, Anambra state Postal Code"},"content":{"rendered":"<p>Ajalli \u2013  Uhuana  Orumba North,  Anambra Postal Code and Zip Code<\/p>\n<p><strong>423120<\/strong><\/p>\n<table class=\"table\">\n<tbody>\n<tr>\n<td width=\"200px\">District Name:<\/td>\n<td>District: Ajalli \u2013 Uhuana<\/td>\n<\/tr>\n<tr>\n<td>Town:<\/td>\n<td>Uhuana<\/td>\n<\/tr>\n<tr>\n<td>Local Government Area:<\/td>\n<td>Orumba North L.G.A<\/td>\n<\/tr>\n<tr>\n<td>State:<\/td>\n<td>Anambra State<\/td>\n<\/tr>\n<tr>\n<td>Country<strong>:<\/strong><\/td>\n<td>Nigeria<\/td>\n<\/tr>\n<tr>\n<td>Associated Zip Code<strong>:<\/strong><\/td>\n<td><strong>423120<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>This is the Postal code  and zip code of Ajalli  in  Uhuana town of Uhuana L.G.A of Anambra state.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ajalli \u2013 Uhuana Orumba North, Anambra Postal Code and Zip Code 423120 District Name: District: Ajalli \u2013 Uhuana Town: Uhuana Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423120 This is the Postal code and zip code of Ajalli in Uhuana town of Uhuana L.G.A of Anambra state.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[791,808],"tags":[],"class_list":["post-88145","post","type-post","status-publish","format-standard","hentry","category-anambra-state","category-orumba-north-l-g-a"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paaCEa-mVH","jetpack-related-posts":[{"id":88071,"url":"https:\/\/www.esteegel.com\/zipcode\/ajalli-ajango-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88145,"position":0},"title":"Ajalli &#8211; Ajango, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ajalli \u2013 Ajango Orumba North, Anambra Postal Code and Zip Code 423120 District Name: District: Ajalli \u2013 Ajango Town: Ajango Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423120 This is the Postal code and zip code of Ajalli in Ajango town of Ajango\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88074,"url":"https:\/\/www.esteegel.com\/zipcode\/ajalli-amagu-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88145,"position":1},"title":"Ajalli &#8211; Amagu, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ajalli \u2013 Amagu Orumba North, Anambra Postal Code and Zip Code 423120 District Name: District: Ajalli \u2013 Amagu Town: Amagu Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423120 This is the Postal code and zip code of Ajalli in Amagu town of Amagu\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88091,"url":"https:\/\/www.esteegel.com\/zipcode\/ajalli-ezibegbe-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88145,"position":2},"title":"Ajalli &#8211; Ezibegbe, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ajalli \u2013 Ezibegbe Orumba North, Anambra Postal Code and Zip Code 423120 District Name: District: Ajalli \u2013 Ezibegbe Town: Ezibegbe Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423120 This is the Postal code and zip code of Ajalli in Ezibegbe town of Ezibegbe\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88117,"url":"https:\/\/www.esteegel.com\/zipcode\/ajalli-nkwa-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88145,"position":3},"title":"Ajalli &#8211; Nkwa, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ajalli \u2013 Nkwa Orumba North, Anambra Postal Code and Zip Code 423120 District Name: District: Ajalli \u2013 Nkwa Town: Nkwa Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423120 This is the Postal code and zip code of Ajalli in Nkwa town of Nkwa\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88120,"url":"https:\/\/www.esteegel.com\/zipcode\/ajalli-obinikpa-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88145,"position":4},"title":"Ajalli &#8211; Obinikpa, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ajalli \u2013 Obinikpa Orumba North, Anambra Postal Code and Zip Code 423120 District Name: District: Ajalli \u2013 Obinikpa Town: Obinikpa Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423120 This is the Postal code and zip code of Ajalli in Obinikpa town of Obinikpa\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88127,"url":"https:\/\/www.esteegel.com\/zipcode\/ajalli-ogbiti-orumba-north-anambra-state-postal-code\/","url_meta":{"origin":88145,"position":5},"title":"Ajalli &#8211; Ogbiti, Orumba North, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ajalli \u2013 Ogbiti Orumba North, Anambra Postal Code and Zip Code 423120 District Name: District: Ajalli \u2013 Ogbiti Town: Ogbiti Local Government Area: Orumba North L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423120 This is the Postal code and zip code of Ajalli in Ogbiti town of Ogbiti\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/88145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/comments?post=88145"}],"version-history":[{"count":0,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/88145\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/media?parent=88145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/categories?post=88145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/tags?post=88145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}