{"id":88202,"date":"2018-08-12T22:17:54","date_gmt":"2018-08-12T22:17:54","guid":{"rendered":"https:\/\/www.esteegel.com\/zipcode\/ezira-imeofia-okii-orumba-south-anambra-state-postal-code\/"},"modified":"2018-08-12T22:17:54","modified_gmt":"2018-08-12T22:17:54","slug":"ezira-imeofia-okii-orumba-south-anambra-state-postal-code","status":"publish","type":"post","link":"https:\/\/www.esteegel.com\/zipcode\/ezira-imeofia-okii-orumba-south-anambra-state-postal-code\/","title":{"rendered":"Ezira &#8211; Imeofia-Okii, Orumba South, Anambra state Postal Code"},"content":{"rendered":"<p>Ezira \u2013  Imeofia-Okii  Orumba South,  Anambra Postal Code and Zip Code<\/p>\n<p><strong>423105<\/strong><\/p>\n<table class=\"table\">\n<tbody>\n<tr>\n<td width=\"200px\">District Name:<\/td>\n<td>District: Ezira \u2013 Imeofia-Okii<\/td>\n<\/tr>\n<tr>\n<td>Town:<\/td>\n<td>Imeofia-Okii<\/td>\n<\/tr>\n<tr>\n<td>Local Government Area:<\/td>\n<td>Orumba South L.G.A<\/td>\n<\/tr>\n<tr>\n<td>State:<\/td>\n<td>Anambra State<\/td>\n<\/tr>\n<tr>\n<td>Country<strong>:<\/strong><\/td>\n<td>Nigeria<\/td>\n<\/tr>\n<tr>\n<td>Associated Zip Code<strong>:<\/strong><\/td>\n<td><strong>423105<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>This is the Postal code  and zip code of Ezira  in  Imeofia-Okii town of Imeofia-Okii L.G.A of Anambra state.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ezira \u2013 Imeofia-Okii Orumba South, Anambra Postal Code and Zip Code 423105 District Name: District: Ezira \u2013 Imeofia-Okii Town: Imeofia-Okii Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423105 This is the Postal code and zip code of Ezira in Imeofia-Okii town of Imeofia-Okii L.G.A of Anambra state.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[791,809],"tags":[],"class_list":["post-88202","post","type-post","status-publish","format-standard","hentry","category-anambra-state","category-orumba-south-l-g-a"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paaCEa-mWC","jetpack-related-posts":[{"id":88224,"url":"https:\/\/www.esteegel.com\/zipcode\/ezira-obuotu-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88202,"position":0},"title":"Ezira &#8211; Obuotu, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ezira \u2013 Obuotu Orumba South, Anambra Postal Code and Zip Code 423105 District Name: District: Ezira \u2013 Obuotu Town: Obuotu Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423105 This is the Postal code and zip code of Ezira in Obuotu town of Obuotu\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88237,"url":"https:\/\/www.esteegel.com\/zipcode\/ezira-ubaha-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88202,"position":1},"title":"Ezira &#8211; Ubaha, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ezira \u2013 Ubaha Orumba South, Anambra Postal Code and Zip Code 423105 District Name: District: Ezira \u2013 Ubaha Town: Ubaha Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423105 This is the Postal code and zip code of Ezira in Ubaha town of Ubaha\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88276,"url":"https:\/\/www.esteegel.com\/zipcode\/ezira-umuoram-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88202,"position":2},"title":"Ezira &#8211; Umuoram, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ezira \u2013 Umuoram Orumba South, Anambra Postal Code and Zip Code 423105 District Name: District: Ezira \u2013 Umuoram Town: Umuoram Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423105 This is the Postal code and zip code of Ezira in Umuoram town of Umuoram\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":87885,"url":"https:\/\/www.esteegel.com\/zipcode\/nimo-ezira-njikoka-anambra-state-postal-code\/","url_meta":{"origin":88202,"position":3},"title":"Nimo &#8211; Ezira, Njikoka, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Nimo \u2013 Ezira Njikoka, Anambra Postal Code and Zip Code 421102 District Name: District: Nimo \u2013 Ezira Town: Ezira Local Government Area: Njikoka L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 421102 This is the Postal code and zip code of Nimo in Ezira town of Ezira L.G.A of\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88186,"url":"https:\/\/www.esteegel.com\/zipcode\/ogboji-amangwu-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88202,"position":4},"title":"Ogboji &#8211; Amangwu, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ogboji \u2013 Amangwu Orumba South, Anambra Postal Code and Zip Code 423114 District Name: District: Ogboji \u2013 Amangwu Town: Amangwu Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423114 This is the Postal code and zip code of Ogboji in Amangwu town of Amangwu\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88187,"url":"https:\/\/www.esteegel.com\/zipcode\/ihite-amaoji-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88202,"position":5},"title":"Ihite &#8211; Amaoji, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Ihite \u2013 Amaoji Orumba South, Anambra Postal Code and Zip Code 423102 District Name: District: Ihite \u2013 Amaoji Town: Amaoji Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423102 This is the Postal code and zip code of Ihite in Amaoji town of Amaoji\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/88202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/comments?post=88202"}],"version-history":[{"count":0,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/88202\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/media?parent=88202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/categories?post=88202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/tags?post=88202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}