{"id":88233,"date":"2018-08-12T22:17:54","date_gmt":"2018-08-12T22:17:54","guid":{"rendered":"https:\/\/www.esteegel.com\/zipcode\/eziagu-omumueji-orumba-south-anambra-state-postal-code\/"},"modified":"2018-08-12T22:17:54","modified_gmt":"2018-08-12T22:17:54","slug":"eziagu-omumueji-orumba-south-anambra-state-postal-code","status":"publish","type":"post","link":"https:\/\/www.esteegel.com\/zipcode\/eziagu-omumueji-orumba-south-anambra-state-postal-code\/","title":{"rendered":"Eziagu &#8211; Omumueji, Orumba South, Anambra state Postal Code"},"content":{"rendered":"<p>Eziagu \u2013  Omumueji  Orumba South,  Anambra Postal Code and Zip Code<\/p>\n<p><strong>423106<\/strong><\/p>\n<table class=\"table\">\n<tbody>\n<tr>\n<td width=\"200px\">District Name:<\/td>\n<td>District: Eziagu \u2013 Omumueji<\/td>\n<\/tr>\n<tr>\n<td>Town:<\/td>\n<td>Omumueji<\/td>\n<\/tr>\n<tr>\n<td>Local Government Area:<\/td>\n<td>Orumba South L.G.A<\/td>\n<\/tr>\n<tr>\n<td>State:<\/td>\n<td>Anambra State<\/td>\n<\/tr>\n<tr>\n<td>Country<strong>:<\/strong><\/td>\n<td>Nigeria<\/td>\n<\/tr>\n<tr>\n<td>Associated Zip Code<strong>:<\/strong><\/td>\n<td><strong>423106<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>This is the Postal code  and zip code of Eziagu  in  Omumueji town of Omumueji L.G.A of Anambra state.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eziagu \u2013 Omumueji Orumba South, Anambra Postal Code and Zip Code 423106 District Name: District: Eziagu \u2013 Omumueji Town: Omumueji Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423106 This is the Postal code and zip code of Eziagu in Omumueji town of Omumueji L.G.A of Anambra state.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[791,809],"tags":[],"class_list":["post-88233","post","type-post","status-publish","format-standard","hentry","category-anambra-state","category-orumba-south-l-g-a"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paaCEa-mX7","jetpack-related-posts":[{"id":88188,"url":"https:\/\/www.esteegel.com\/zipcode\/eziagu-amokwe-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88233,"position":0},"title":"Eziagu &#8211; Amokwe, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Eziagu \u2013 Amokwe Orumba South, Anambra Postal Code and Zip Code 423106 District Name: District: Eziagu \u2013 Amokwe Town: Amokwe Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423106 This is the Postal code and zip code of Eziagu in Amokwe town of Amokwe\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88218,"url":"https:\/\/www.esteegel.com\/zipcode\/eziagu-obeagu-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88233,"position":1},"title":"Eziagu &#8211; Obeagu, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Eziagu \u2013 Obeagu Orumba South, Anambra Postal Code and Zip Code 423106 District Name: District: Eziagu \u2013 Obeagu Town: Obeagu Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423106 This is the Postal code and zip code of Eziagu in Obeagu town of Obeagu\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88252,"url":"https:\/\/www.esteegel.com\/zipcode\/eziagu-umueleke-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88233,"position":2},"title":"Eziagu &#8211; Umueleke, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Eziagu \u2013 Umueleke Orumba South, Anambra Postal Code and Zip Code 423106 District Name: District: Eziagu \u2013 Umueleke Town: Umueleke Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423106 This is the Postal code and zip code of Eziagu in Umueleke town of Umueleke\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88262,"url":"https:\/\/www.esteegel.com\/zipcode\/eziagu-umumbaka-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88233,"position":3},"title":"Eziagu &#8211; Umumbaka, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Eziagu \u2013 Umumbaka Orumba South, Anambra Postal Code and Zip Code 423106 District Name: District: Eziagu \u2013 Umumbaka Town: Umumbaka Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423106 This is the Postal code and zip code of Eziagu in Umumbaka town of Umumbaka\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88266,"url":"https:\/\/www.esteegel.com\/zipcode\/eziagu-umunwozo-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88233,"position":4},"title":"Eziagu &#8211; Umunwozo, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Eziagu \u2013 Umunwozo Orumba South, Anambra Postal Code and Zip Code 423106 District Name: District: Eziagu \u2013 Umunwozo Town: Umunwozo Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423106 This is the Postal code and zip code of Eziagu in Umunwozo town of Umunwozo\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88267,"url":"https:\/\/www.esteegel.com\/zipcode\/eziagu-umunwozonde-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88233,"position":5},"title":"Eziagu &#8211; Umunwozonde, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Eziagu \u2013 Umunwozonde Orumba South, Anambra Postal Code and Zip Code 423106 District Name: District: Eziagu \u2013 Umunwozonde Town: Umunwozonde Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423106 This is the Postal code and zip code of Eziagu in Umunwozonde town of Umunwozonde\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/88233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/comments?post=88233"}],"version-history":[{"count":0,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/88233\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/media?parent=88233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/categories?post=88233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/tags?post=88233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}