{"id":88259,"date":"2018-08-12T22:17:54","date_gmt":"2018-08-12T22:17:54","guid":{"rendered":"https:\/\/www.esteegel.com\/zipcode\/nawfija-umuezeogbu-orumba-south-anambra-state-postal-code\/"},"modified":"2018-08-12T22:17:54","modified_gmt":"2018-08-12T22:17:54","slug":"nawfija-umuezeogbu-orumba-south-anambra-state-postal-code","status":"publish","type":"post","link":"https:\/\/www.esteegel.com\/zipcode\/nawfija-umuezeogbu-orumba-south-anambra-state-postal-code\/","title":{"rendered":"Nawfija &#8211; Umuezeogbu, Orumba South, Anambra state Postal Code"},"content":{"rendered":"<p>Nawfija \u2013  Umuezeogbu  Orumba South,  Anambra Postal Code and Zip Code<\/p>\n<p><strong>423115<\/strong><\/p>\n<table class=\"table\">\n<tbody>\n<tr>\n<td width=\"200px\">District Name:<\/td>\n<td>District: Nawfija \u2013 Umuezeogbu<\/td>\n<\/tr>\n<tr>\n<td>Town:<\/td>\n<td>Umuezeogbu<\/td>\n<\/tr>\n<tr>\n<td>Local Government Area:<\/td>\n<td>Orumba South L.G.A<\/td>\n<\/tr>\n<tr>\n<td>State:<\/td>\n<td>Anambra State<\/td>\n<\/tr>\n<tr>\n<td>Country<strong>:<\/strong><\/td>\n<td>Nigeria<\/td>\n<\/tr>\n<tr>\n<td>Associated Zip Code<strong>:<\/strong><\/td>\n<td><strong>423115<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>This is the Postal code  and zip code of Nawfija  in  Umuezeogbu town of Umuezeogbu L.G.A of Anambra state.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nawfija \u2013 Umuezeogbu Orumba South, Anambra Postal Code and Zip Code 423115 District Name: District: Nawfija \u2013 Umuezeogbu Town: Umuezeogbu Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423115 This is the Postal code and zip code of Nawfija in Umuezeogbu town of Umuezeogbu L.G.A of Anambra state.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[791,809],"tags":[],"class_list":["post-88259","post","type-post","status-publish","format-standard","hentry","category-anambra-state","category-orumba-south-l-g-a"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paaCEa-mXx","jetpack-related-posts":[{"id":88189,"url":"https:\/\/www.esteegel.com\/zipcode\/nawfija-amokwu-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88259,"position":0},"title":"Nawfija &#8211; Amokwu, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Nawfija \u2013 Amokwu Orumba South, Anambra Postal Code and Zip Code 423115 District Name: District: Nawfija \u2013 Amokwu Town: Amokwu Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423115 This is the Postal code and zip code of Nawfija in Amokwu town of Amokwu\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88197,"url":"https:\/\/www.esteegel.com\/zipcode\/nawfija-ezeome-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88259,"position":1},"title":"Nawfija &#8211; Ezeome, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Nawfija \u2013 Ezeome Orumba South, Anambra Postal Code and Zip Code 423115 District Name: District: Nawfija \u2013 Ezeome Town: Ezeome Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423115 This is the Postal code and zip code of Nawfija in Ezeome town of Ezeome\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88227,"url":"https:\/\/www.esteegel.com\/zipcode\/nawfija-ohukabia-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88259,"position":2},"title":"Nawfija &#8211; Ohukabia, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Nawfija \u2013 Ohukabia Orumba South, Anambra Postal Code and Zip Code 423115 District Name: District: Nawfija \u2013 Ohukabia Town: Ohukabia Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423115 This is the Postal code and zip code of Nawfija in Ohukabia town of Ohukabia\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88248,"url":"https:\/\/www.esteegel.com\/zipcode\/nawfija-umuawahi-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88259,"position":3},"title":"Nawfija &#8211; Umuawahi, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Nawfija \u2013 Umuawahi Orumba South, Anambra Postal Code and Zip Code 423115 District Name: District: Nawfija \u2013 Umuawahi Town: Umuawahi Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423115 This is the Postal code and zip code of Nawfija in Umuawahi town of Umuawahi\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88258,"url":"https:\/\/www.esteegel.com\/zipcode\/nawfija-umuezeiyi-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88259,"position":4},"title":"Nawfija &#8211; Umuezeiyi, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Nawfija \u2013 Umuezeiyi Orumba South, Anambra Postal Code and Zip Code 423115 District Name: District: Nawfija \u2013 Umuezeiyi Town: Umuezeiyi Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423115 This is the Postal code and zip code of Nawfija in Umuezeiyi town of Umuezeiyi\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88273,"url":"https:\/\/www.esteegel.com\/zipcode\/nawfija-umuoma-orumba-south-anambra-state-postal-code\/","url_meta":{"origin":88259,"position":5},"title":"Nawfija &#8211; Umuoma, Orumba South, Anambra state Postal Code","author":"admin","date":"August 12, 2018","format":false,"excerpt":"Nawfija \u2013 Umuoma Orumba South, Anambra Postal Code and Zip Code 423115 District Name: District: Nawfija \u2013 Umuoma Town: Umuoma Local Government Area: Orumba South L.G.A State: Anambra State Country: Nigeria Associated Zip Code: 423115 This is the Postal code and zip code of Nawfija in Umuoma town of Umuoma\u2026","rel":"","context":"In &quot;Anambra State&quot;","block_context":{"text":"Anambra State","link":"https:\/\/www.esteegel.com\/zipcode\/category\/anambra-state\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/88259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/comments?post=88259"}],"version-history":[{"count":0,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/posts\/88259\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/media?parent=88259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/categories?post=88259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esteegel.com\/zipcode\/wp-json\/wp\/v2\/tags?post=88259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}